{"id":4026,"date":"2021-09-15T18:05:02","date_gmt":"2021-09-15T16:05:02","guid":{"rendered":"https:\/\/candela-ptb.de\/?p=4026"},"modified":"2023-08-02T11:47:27","modified_gmt":"2023-08-02T09:47:27","slug":"innovationen-im-westbalkan-qi-einrichtungen-reagieren-auf-die-corona-pandemie","status":"publish","type":"post","link":"https:\/\/candela-ptb.de\/de\/innovationen-im-westbalkan-qi-einrichtungen-reagieren-auf-die-corona-pandemie\/","title":{"rendered":"Innovationen im Westbalkan. QI-Einrichtungen reagieren auf die Corona-Pandemie"},"content":{"rendered":"\n<p>Die vielen Herausforderungen durch die Covid-19-Pandemie haben nicht nur zu kurzfristigen Ver\u00e4nderungen gef\u00fchrt. Sie k\u00f6nnten ebenso langfristige Innovationen hervorbringen. Das zeigt beispielsweise ein Blick in die westlichen Balkanl\u00e4nder. Im M\u00e4rz 2021 veranstaltete die PTB einen virtuellen Erfahrungsaustausch \u00fcber Innovationen in Institutionen und Dienstleistungen der Qualit\u00e4tsinfrastruktur, kurz QI, in den L\u00e4ndern des westlichen Balkans. Mehr als 30 Teilnehmende aus Metrologieinstituten, Normungsgremien und Akkreditierungsstellen waren dabei. Pr\u00e4sentiert und diskutiert wurden Innovationsaktivit\u00e4ten mit dem Ziel, diese nachhaltig zu f\u00f6rdern.<\/p>\n\n\n\n<p>Der virtuelle Erfahrungsaustausch hat gezeigt, dass fast alle QI-Einrichtungen im Westbalkan die gleichen Herausforderungen hatten. Der pl\u00f6tzliche Einbruch der Pandemie traf sie unvorbereitet, sodass viele Standardprozesse nicht wie gewohnt durchgef\u00fchrt werden konnten. Nach und wurde zudem klar, dass die Pandemie l\u00e4nger dauert als anfangs angenommen. Aus dem anf\u00e4nglichen Abwarten musste ein Handeln werden. Durch die Innovationen, die sich daraus ergeben haben, war es den QI-Einrichtungen m\u00f6glich, w\u00e4hrend der Pandemie handlungsf\u00e4hig zu bleiben. W\u00e4hrend des virtuellen Austausches richtete sich der Blick nicht auf g\u00e4nzlich neue Dienstleistungen, sondern vielmehr auf die Entwicklung neuer Wege zur Durchf\u00fchrung bereits bestehender Arbeitsprozesse.<\/p>\n\n\n\n<p>Hands-on Laboratory Training und Kampagnen zur Erh\u00f6hung der Sichtbarkeit<\/p>\n\n\n\n<p>Ein Beispiel ist die Umstellung von Laborschulungen vor Ort auf Remote-Schulungen. Mitarbeitende des Instituts f\u00fcr Metrologie von Bosnien und Herzegowina nahmen an einem Remote Hands-on Laboratory Training teil. Die Inhalte wurden per Videostreaming aus dem Labor und per LabView vermittelt. LabView ist eine Anwendung, die die Automatisierung von Messungen erm\u00f6glicht. Die positiven Reaktionen der Teilnehmenden zeigen: \u00a0Remote Hands-on Laboratory Trainings sind nicht nur eine Notl\u00f6sung, sondern k\u00f6nnen auch nach der Pandemie Anwendung finden. Aufgrund der eing\u00e4ngigen Vorbereitung empfanden viele die Fernschulung als interaktiver und effizienter. Dar\u00fcber hinaus wurde der hohe Grad an eigenverantwortlichem Arbeiten bei der Umsetzung der einzelnen Schritte als positiv wahrgenommen.<\/p>\n\n\n\n<p>Wie man durch Kampagnen und Wettbewerbe seinen Bekanntheitsgrad erheblich steigern kann, zeigte das Montenegrische Amt f\u00fcr Metrologie. Die Unterst\u00fctzung der Kampagne <em>Stay at home<\/em> brachte beispielsweise einen Wettbewerb \u00fcber Kochmessungen f\u00fcr Kleinkinder hervor sowie eine wissenschaftliche Kampagne f\u00fcr Gymnasiast*innen. Die Aktivit\u00e4ten erhielten gro\u00dfe mediale Aufmerksamkeit und steigerten die Sichtbarkeit des Eichamtes. F\u00fcr die Zukunft sind weitere Aktivit\u00e4ten geplant wie die Entwicklung digitaler Kalibrierungszertifikate oder die Einrichtung einer E-Learning-Plattform.<\/p>\n\n\n\n<p>Remote Peer Evaluation<\/p>\n\n\n\n<p>Evaluationen sind f\u00fcr Akkreditierungsstellen ein entscheidender Meilenstein im Hinblick auf die internationale Anerkennung ihrer Dienste. Die Herausforderung, die sich w\u00e4hrend der Covid-19-Pandemie ergeben hat, ist die Begutachtung aus der Ferne. Im Februar 2021 wurde die albanische Generaldirektion f\u00fcr Akkreditierung, kurz DPA, bewertet. Durchgef\u00fchrt wurde die Evaluation von der Europ\u00e4ischen Akkreditierungsstelle. Die gr\u00f6\u00dfte Herausforderung beim Prozess der Remote Peer Evaluation war die Verf\u00fcgbarkeit einer stabilen und schnellen Internetverbindung. Eine andere \u00f6ffentliche Einrichtung unterst\u00fctzte die DPA dabei und stellte zudem eine Videokonferenzplattform bereit. Die DPA stellte f\u00fcr den Besuch vor Ort Tablets und Smartphones zur Verf\u00fcgung, beauftragte ein externes Unternehmen mit dem Betrieb der Kameras und sorgte durch die Bereitstellung von Dolmetscher*innen f\u00fcr eine reibungslose Kommunikation. Die Durchf\u00fchrung dieser Innovation war sehr erfolgreich, wozu vor allem zwei Faktoren entscheidend beigetragen haben. Die Vorbereitungen f\u00fcr die Durchf\u00fchrung der Remote Evaluation hatten bereits vor der Pandemie begonnen. Zudem verf\u00fcgte die DPA bereits \u00fcber ein Online-System f\u00fcr Kundenbeziehungen, mit dem alle Akkreditierungsschritte durchgef\u00fchrt werden konnten.<\/p>\n\n\n\n<p>Innovation in Normungsinstituten als Hilfe in der Covid-19-Pandemie<\/p>\n\n\n\n<p>Das Normungsinstitut der Republik Nordmazedonien, kurz ISRSM, stellte vor\u00fcbergehend 18 Normen f\u00fcr Schutz- und Medizinprodukte sowie An\u00e4sthesie- und Beatmungsger\u00e4te zur Verf\u00fcgung. 30 weitere ISO-Normen wurden auf der ISO-Website zum kostenlosen Download bereitgestellt. Zwar wurden durch die kostenlose Bereitstellung einige Einnahmen eingeb\u00fc\u00dft, allerdings konnte das Institut seinen Bekanntheitsgrad in der Gesch\u00e4ftswelt steigern, beispielsweise durch Werbung f\u00fcr die kostenfreien Normen auf der Website der nordmazedonischen Handelskammer.<\/p>\n\n\n\n<p>Eine weitere Innovation war die \u00fcberaus kurzfristige Annahme eines Dokuments des Europ\u00e4ischen Kommitees f\u00fcr Normung, kurz CEN. Es handelt sich dabei um das CEN Workshop Agreement 17553: <em>Community face coverings &#8211; Guide to minimum requirements, methods of testing and use<\/em>. Als Ergebnis der Entwicklung eines gesamteurop\u00e4ischen Verfahrens konnte es innerhalb von nur drei Monaten verabschiedet werden.<\/p>\n\n\n\n<p>Gemeinsame Herausforderungen f\u00fcr Innovation<\/p>\n\n\n\n<p>Was durch die Situation in der Pandemie angesto\u00dfen wurde, soll weiterhin Anwendung finden. Innovative Aktivit\u00e4ten sollen stark gef\u00f6rdert werden. Neben den hier angef\u00fchrten Beispielen von Remote Dienstleistungen und Kampagnen zur Erh\u00f6hung der Sichtbarkeit wurden als weitere innovative Entwicklungen die Umstellung auf die Bereitstellung von E-Schulungen und die Digitalisierung von Dienstleistungen, Online-Sitzungen von technischen Aussch\u00fcssen sowie die generelle Online-Kommunikation mit Interessengruppen genannt.<\/p>\n\n\n\n<p>Der ausf\u00fchrliche Bericht zum virtuellen Erfahrungsaustausch kann unter folgendem Link eingesehen werden:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.covid19.ptb.de\/economy\/innovation\">https:\/\/www.covid19.ptb.de\/economy\/innovation<\/a><\/p>\n\n\n\n<p>Foto: Istock<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die vielen Herausforderungen durch die Covid-19-Pandemie haben nicht nur zu kurzfristigen Ver\u00e4nderungen gef\u00fchrt. Sie k\u00f6nnten ebenso langfristige Innovationen hervorbringen. Das zeigt beispielsweise ein Blick in die westlichen Balkanl\u00e4nder. Im M\u00e4rz 2021 veranstaltete die PTB einen virtuellen Erfahrungsaustausch \u00fcber Innovationen in Institutionen und Dienstleistungen der Qualit\u00e4tsinfrastruktur, kurz QI, in den L\u00e4ndern des westlichen Balkans. Mehr als&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4022,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[341],"tags":[],"class_list":["post-4026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-341","description-off"],"_links":{"self":[{"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/posts\/4026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/comments?post=4026"}],"version-history":[{"count":5,"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/posts\/4026\/revisions"}],"predecessor-version":[{"id":4090,"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/posts\/4026\/revisions\/4090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/media\/4022"}],"wp:attachment":[{"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/media?parent=4026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/categories?post=4026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candela-ptb.de\/de\/wp-json\/wp\/v2\/tags?post=4026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}