{"id":5148,"date":"2022-11-30T16:18:37","date_gmt":"2022-11-30T15:18:37","guid":{"rendered":"https:\/\/candela-ptb.de\/?p=5148"},"modified":"2023-08-02T11:51:46","modified_gmt":"2023-08-02T09:51:46","slug":"la-metrologie-en-pratique-une-delegation-tunisienne-invitee-a-braunschweig","status":"publish","type":"post","link":"https:\/\/candela-ptb.de\/fr\/la-metrologie-en-pratique-une-delegation-tunisienne-invitee-a-braunschweig\/","title":{"rendered":"La m\u00e9trologie en pratique\u00a0: Une d\u00e9l\u00e9gation tunisienne invit\u00e9e \u00e0 Braunschweig"},"content":{"rendered":"\n<p>Comment int\u00e9grer des contenus ax\u00e9s sur la pratique aux cursus universitaires de m\u00e9trologie&nbsp;? Afin de r\u00e9pondre \u00e0 cette question, 15&nbsp;professeur\u00b7e\u00b7s de l\u2019enseignement sup\u00e9rieur ont visit\u00e9 le PTB \u00e0 Braunschweig lors d\u2019un voyage d\u2019\u00e9tudes du&nbsp;10&nbsp;au&nbsp;14&nbsp;octobre. La d\u00e9l\u00e9gation s\u2019est pench\u00e9e sur cette probl\u00e9matique dans le cadre du projet \u00ab&nbsp;D\u00e9veloppement des comp\u00e9tences pour l\u2019assurance qualit\u00e9 dans le domaine des exports en Tunisie&nbsp;\u00bb financ\u00e9 par le BMZ.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"892\" src=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/D2671_004-1024x892.jpg\" alt=\"Un groupe de personnes se tient sur un escalier et pose pour une photo de groupe.\" class=\"wp-image-5134\" srcset=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/D2671_004-1024x892.jpg 1024w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/D2671_004-300x261.jpg 300w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/D2671_004-768x669.jpg 768w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/D2671_004-1536x1338.jpg 1536w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/D2671_004.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Des professeurs et enseignants de 12 universit\u00e9s tunisiennes en visite au PTB.<\/em><\/figcaption><\/figure>\n\n\n\n<p>Afin d\u2019acc\u00e9l\u00e9rer le d\u00e9veloppement des comp\u00e9tences pour une qualification r\u00e9pondant aux besoins dans le domaine de la m\u00e9trologie, le PTB soutient huit laboratoires pilotes de l\u2019enseignement sup\u00e9rieur. Dans ce contexte, une contribution \u00e0 l\u2019aspect pratique de l\u2019enseignement est faite en facilitant l\u2019acquisition de mat\u00e9riel de laboratoire sp\u00e9cialis\u00e9. Le PTB accompagne \u00e9galement le d\u00e9veloppement de modules de m\u00e9trologie ax\u00e9s sur la pratique qui sont d\u00e9j\u00e0 int\u00e9gr\u00e9s aux cursus d\u2019ing\u00e9nierie existants. Et ce type de soutien porte ses fruits&nbsp;: Ainsi, un pur cursus de master en m\u00e9trologie intitul\u00e9 \u00ab&nbsp;<em>Industrial metrology and quality control, MICQ<\/em>&nbsp;\u00bb a \u00e9t\u00e9 mis en place au <em>Higher Institute of Technological Studies of Sousse<\/em>, ville jumel\u00e9e avec Braunschweig. Ce cursus est unique en son genre en Tunisie.<\/p>\n\n\n\n<p>Le PTB a con\u00e7u le programme de ce voyage d\u2019\u00e9tude en collaboration avec l\u2019universit\u00e9 technique de Braunschweig (TU Braunschweig) afin que nos amis tunisiens puissent se faire une id\u00e9e de la mani\u00e8re dont l\u2019enseignement de la m\u00e9trologie est organis\u00e9 au niveau universitaire ici \u00e0 Braunschweig. L\u2019une des questions centrales dans ce contexte \u00e9tait de savoir comment les contenus ax\u00e9s sur la pratiques sont enseign\u00e9s. Une autre question \u00e9tait de savoir comment pr\u00e9parer les \u00e9tudiant\u00b7e\u00b7s aux besoins de l\u2019industrie en mati\u00e8re d\u2019assurance et de gestion de la qualit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06930-1024x576.jpg\" alt=\"Un groupe de personnes est assis dans une salle de r\u00e9union. Un homme fait une pr\u00e9sentation devant lui.\" class=\"wp-image-5124\" srcset=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06930-1024x576.jpg 1024w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06930-300x169.jpg 300w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06930-768x432.jpg 768w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06930-1536x864.jpg 1536w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06930.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>En visite \u00e0 Carl Zeiss Metrology GmbH<\/em><\/figcaption><\/figure>\n\n\n\n<p>En tant que coordinateur du cursus, D<sup>r<\/sup> Marc Fischer a pr\u00e9sent\u00e9 le cursus de master \u00ab&nbsp;M\u00e9trologie et Technologies de Mesure&nbsp;\u00bb. La d\u00e9l\u00e9gation tunisienne a en outre visit\u00e9 l\u2019Usine d\u2019apprentissage pour une production num\u00e9rique et durable de l\u2019Institut pour machines-outils et techniques de production. Le professeur Meinhard Schilling, directeur de l\u2019Institut de m\u00e9trologie \u00e9lectrique et des principes de base de l\u2019\u00e9lectrotechnique, a en outre pr\u00e9sent\u00e9 l\u2019\u00e9cole doctorale de Braunschweig \u00ab&nbsp;International Graduate School of Metrology&nbsp;\u00bb.<\/p>\n\n\n\n<p>Le professeur D<sup>r<\/sup>&nbsp;Marcus Petz de l&#8217;Institut de m\u00e9trologie en production a introduit les proc\u00e9d\u00e9s de mesure optiques, une pr\u00e9sentation qui a \u00e9t\u00e9 compl\u00e9t\u00e9e par une visite de la soci\u00e9t\u00e9 Carl Zeiss GOM Metrology&nbsp;GmbH. Cette entreprise, dont la sp\u00e9cialit\u00e9 sont les mat\u00e9riels et logiciels de m\u00e9trologie industrielle en 3D, a donn\u00e9 un bon aper\u00e7u de ses activit\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06928-1024x576.jpg\" alt=\"Un groupe de personnes est assis dans une salle de r\u00e9union. Un homme fait une pr\u00e9sentation devant lui.\" class=\"wp-image-5129\" srcset=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06928-1024x576.jpg 1024w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06928-300x169.jpg 300w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06928-768x432.jpg 768w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06928-1536x864.jpg 1536w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/DSC06928.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>En visite \u00e0 Carl Zeiss Metrology GmbH<\/em><\/figcaption><\/figure>\n\n\n\n<p>Outre cet aper\u00e7u de l\u2019enseignement sup\u00e9rieur, la visite de divers laboratoires sp\u00e9cialis\u00e9s du PTB (modules solaires, technique de mesure des coordonn\u00e9es, r\u00e9alisation de la force et acoustique appliqu\u00e9e) \u00e9tait \u00e9galement au programme.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Et m\u00eame une seconde d\u00e9l\u00e9gation tunisienne&nbsp;!<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"830\" src=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/Gruppenfoto-1024x830.jpg\" alt=\"Un groupe de personnes se tient sur un escalier et pose pour une photo de groupe.\" class=\"wp-image-5119\" srcset=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/Gruppenfoto-1024x830.jpg 1024w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/Gruppenfoto-300x243.jpg 300w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/Gruppenfoto-768x622.jpg 768w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/Gruppenfoto-1536x1245.jpg 1536w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/Gruppenfoto-76x61.jpg 76w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2016\/11\/Gruppenfoto.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Les membres du comit\u00e9 de pilotage du projet tuniso-allemand d&#8217;assurance qualit\u00e9 en visite au PTB.<\/em><\/figcaption><\/figure>\n\n\n\n<p>Mais cette d\u00e9l\u00e9gation tunisienne n\u2019\u00e9tait pas la seule cette ann\u00e9e. Du 18&nbsp;au&nbsp;21&nbsp;juillet, nous avions d\u00e9j\u00e0 eu le plaisir d\u2019accueillir un groupe de 14&nbsp;personnes.<\/p>\n\n\n\n<p>Ce groupe se composait de membres du comit\u00e9 de projet ainsi que de repr\u00e9sentant\u00b7e\u00b7s du Minist\u00e8re de l\u2019industrie, du Minist\u00e8re du Commerce, des associations professionnelles UTICA<sup>1<\/sup> et CONECT<sup>2<\/sup> International, de l\u2019organisme national d\u2019accr\u00e9ditation TUNAC, de l\u2019Institut national de m\u00e9trologie tunisien ANM, des Minist\u00e8res de l\u2019emploi et de l\u2019enseignement sup\u00e9rieur ainsi que du Laboratoire national de m\u00e9trologie chimique (LNMc-INRAP).<\/p>\n\n\n\n<p>Lors de ce voyage d\u2019\u00e9tude d\u2019une dur\u00e9e d\u2019une semaine a eu lieu la r\u00e9union annuelle du comit\u00e9 de pilotage. Suite \u00e0 cette r\u00e9union, un programme vari\u00e9 attendait nos invit\u00e9\u00b7e\u00b7s avec de nombreux th\u00e8mes particuli\u00e8rement int\u00e9ressants. Le groupe a tout d\u2019abord \u00e9t\u00e9 accueilli par le vice-pr\u00e9sident du PTB, Prof. D<sup>r<\/sup>&nbsp;Frank H\u00e4rtig, qui a propos\u00e9 un aper\u00e7u g\u00e9n\u00e9ral ainsi qu\u2019un historique du PTB.<\/p>\n\n\n\n<p>Ont suivi diverses visites de laboratoires. La d\u00e9l\u00e9gation s\u2019est tout d\u2019abord rendue sur le site du laboratoire priv\u00e9 d\u2019\u00e9talonnage et d\u2019essais Perschmann&nbsp;GmbH \u00e0 Braunschweig. Puis, D<sup>r<\/sup>&nbsp;Shanna Sch\u00f6nhals a fait le point sur le stade de d\u00e9veloppement du projet du PTB concernant l\u2019introduction du certificat num\u00e9rique d\u2019\u00e9talonnage. Puis, le groupe a visit\u00e9 le laboratoire du PTB \u00ab&nbsp;Entra\u00eenements \u00e9lectriques antid\u00e9flagrants&nbsp;\u00bb. Ce voyage s\u2019est termin\u00e9 par des \u00e9changes avec l\u2019association professionnelle \u00e9lectrotechnique, \u00e9lectronique et informatique (VDE) et la visite de ses laboratoires d\u2019essais \u00e0 Offenbach am Main.<\/p>\n\n\n\n<p>Outre les rendez-vous officiels, ce voyage a permis des dialogues concernant la mise en \u0153uvre des activit\u00e9s li\u00e9es au projet.<\/p>\n\n\n\n<p>Droits d\u2019auteurs pour les photos&nbsp;: Carl ZEISS Metrology GmbH et PTB.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment int\u00e9grer des contenus ax\u00e9s sur la pratique aux cursus universitaires de m\u00e9trologie&nbsp;? Afin de r\u00e9pondre \u00e0 cette question, 15&nbsp;professeur\u00b7e\u00b7s de l\u2019enseignement sup\u00e9rieur ont visit\u00e9 le PTB \u00e0 Braunschweig lors d\u2019un voyage d\u2019\u00e9tudes du&nbsp;10&nbsp;au&nbsp;14&nbsp;octobre. La d\u00e9l\u00e9gation s\u2019est pench\u00e9e sur cette probl\u00e9matique dans le cadre du projet \u00ab&nbsp;D\u00e9veloppement des comp\u00e9tences pour l\u2019assurance qualit\u00e9 dans le domaine&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[413,482],"tags":[486,485,380,484,487],"class_list":["post-5148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-afrique-du-nord-et-proche-orient","category-amities","tag-cursus","tag-developpement-des-competences-fr","tag-metrologie-fr","tag-tu-braunschweig-fr","tag-tunisie","category-413","category-482","description-off"],"_links":{"self":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts\/5148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/comments?post=5148"}],"version-history":[{"count":7,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts\/5148\/revisions"}],"predecessor-version":[{"id":5246,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts\/5148\/revisions\/5246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/media\/5139"}],"wp:attachment":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/media?parent=5148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/categories?post=5148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/tags?post=5148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}