{"id":6427,"date":"2024-04-29T15:09:57","date_gmt":"2024-04-29T13:09:57","guid":{"rendered":"https:\/\/candela-ptb.de\/?p=6427"},"modified":"2024-04-29T14:46:02","modified_gmt":"2024-04-29T12:46:02","slug":"la-boite-a-outils-calidena-parle-maintenant-francais","status":"publish","type":"post","link":"https:\/\/candela-ptb.de\/fr\/la-boite-a-outils-calidena-parle-maintenant-francais\/","title":{"rendered":"La bo\u00eete \u00e0 outils Calidena parle maintenant fran\u00e7ais\u00a0!"},"content":{"rendered":"\n<p>La bo\u00eete \u00e0 outils Calidena est maintenant disponible en fran\u00e7ais\u00a0! La bo\u00eete \u00e0 outils est un support facilitant l\u2019utilisation du <a href=\"https:\/\/www.ic.ptb.de\/media\/fileadmin\/Publications\/PTB_Info_Calidena_FR.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Manuel Calidena\u00a02.0<\/a>\u00a0; elle fait partie int\u00e9grante de la m\u00e9thode Calidena visant \u00e0 promouvoir la qualit\u00e9 au sein des cha\u00eenes de valeur. Calidena est une m\u00e9thode participative qui encourage la participation active de toutes les parties prenantes d\u2019une cha\u00eene de valeur dans sa totalit\u00e9 \u00e0 l\u2019analyse de celle-ci. L\u2019objectif central de cette m\u00e9thode est de garantir la qualit\u00e9 et de prouver la conformit\u00e9 de produits ou processus de production. Ces deux aspects sont encourag\u00e9s ou garantis par le biais de prestations des institutions de l\u2019infrastructure qualit\u00e9 (m\u00e9trologie, normalisation, accr\u00e9ditation, certification, etc.). La bo\u00eete \u00e0 outils<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2024\/04\/S_15_Calidena_Training_2020_5BMM_People-34-1024x683.jpg\" alt=\"Trois femmes sont assises ensemble sur des chaises en demi-cercle et sourient. En arri\u00e8re-plan, vous pouvez voir des cloisons de s\u00e9paration sur lesquelles sont fix\u00e9es diverses affiches.\" class=\"wp-image-6448\" srcset=\"https:\/\/candela-ptb.de\/wp-content\/uploads\/2024\/04\/S_15_Calidena_Training_2020_5BMM_People-34-1024x683.jpg 1024w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2024\/04\/S_15_Calidena_Training_2020_5BMM_People-34-300x200.jpg 300w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2024\/04\/S_15_Calidena_Training_2020_5BMM_People-34-768x512.jpg 768w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2024\/04\/S_15_Calidena_Training_2020_5BMM_People-34-1536x1025.jpg 1536w, https:\/\/candela-ptb.de\/wp-content\/uploads\/2024\/04\/S_15_Calidena_Training_2020_5BMM_People-34.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Participants \u00e0 un atelier Calidena. Copyright \u00a9 Christian Schoen<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Calidena s\u2019appuie sur des exp\u00e9riences pratiques r\u00e9alis\u00e9es dans divers pays d\u2019Am\u00e9rique latine et des Cara\u00efbes, d\u2019Asie et d\u2019Afrique et propose un grand nombre d\u2019instructions et d\u2019instruments structur\u00e9s pour correspondre aux diff\u00e9rentes phases d\u2019application de la m\u00e9thode Calidena. Ce document s\u2019adresse aux personnes g\u00e9rant des programmes et projets de d\u00e9veloppement de cha\u00eenes de valeur ou de mise en place et d\u00e9veloppement de l\u2019infrastructure qualit\u00e9 ainsi qu\u2019aux facilitateurs et facilitatrices de processus Calidena. Nous esp\u00e9rons que la version fran\u00e7aise de la Bo\u00eete \u00e0 outils Calidena contribuera \u00e0 une plus grande diffusion et une plus large application de cette m\u00e9thode.<\/p>\n\n\n\n<p>Pour en savoir plus sur la m\u00e9thode Calidena, veuillez consulter le lien suivant https:\/\/www.calidena.ptb.de\/. Vous pouvez t\u00e9l\u00e9charger la brochure <a href=\"https:\/\/www.ic.ptb.de\/media\/fileadmin\/Publications\/PTB_Info_Calidena_Toolbox_FR.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a>.<\/p>\n\n\n\n<p>Copyright \u00a9 PTB\/BM Studio Ltd. Nana Kwame B. Adjei<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La bo\u00eete \u00e0 outils Calidena est maintenant disponible en fran\u00e7ais\u00a0! La bo\u00eete \u00e0 outils est un support facilitant l\u2019utilisation du Manuel Calidena\u00a02.0\u00a0; elle fait partie int\u00e9grante de la m\u00e9thode Calidena visant \u00e0 promouvoir la qualit\u00e9 au sein des cha\u00eenes de valeur. Calidena est une m\u00e9thode participative qui encourage la participation active de toutes les parties&hellip;<\/p>\n","protected":false},"author":1,"featured_media":6422,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[457,440],"tags":[757,756,535],"class_list":["post-6427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calidena-fr","category-publications-fr","tag-calidena-3","tag-chaines-de-valeur","tag-infrastructure-qualite","category-457","category-440","description-off"],"_links":{"self":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts\/6427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/comments?post=6427"}],"version-history":[{"count":3,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts\/6427\/revisions"}],"predecessor-version":[{"id":6453,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts\/6427\/revisions\/6453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/media\/6422"}],"wp:attachment":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/media?parent=6427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/categories?post=6427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/tags?post=6427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}