{"id":542,"count":1,"description":"","link":"https:\/\/candela-ptb.de\/fr\/tag\/effondrement\/","name":"Effondrement","slug":"effondrement","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/tags\/542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/candela-ptb.de\/fr\/wp-json\/wp\/v2\/posts?tags=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}